{"id":4175,"date":"2018-09-12T08:00:19","date_gmt":"2018-09-12T06:00:19","guid":{"rendered":"https:\/\/www.dexeus.com\/blog\/actualidad-de\/8-donnees-qui-vous-interessent-congelation-des-ovules\/"},"modified":"2019-04-04T13:16:39","modified_gmt":"2019-04-04T11:16:39","slug":"einfrieren-eizellen-8-interessente-fakten","status":"publish","type":"post","link":"https:\/\/www.dexeus.com\/blog\/de\/aktuell\/einfrieren-eizellen-8-interessente-fakten\/","title":{"rendered":"Einfrieren von Eizellen: 8 interessente Fakten"},"content":{"rendered":"<h4><span class=\"noticias-h4-azul-oscuro\">Was Sie wissen m\u00fcssen, bevor Sie Ihre Eizellen einfrieren lassen<\/span><\/h4>\n<p>Obwohl immer mehr Frauen ihre Eizellen einfrieren lassen, wird dar\u00fcber kaum gesprochen und es gibt wenige Informationen dar\u00fcber. Auch die \u00c4rzte schlagen das nicht offen vor, weil sie der Meinung sind, dass dies ein pers\u00f6nliche Entscheidung ist. Deshalb haben wir\u00a0<a class=\"enlaces-rosa\" href=\"http:\/\/de.dexeus.com\/lernen-sie-dexeus-kennen\/arzte\/marta-devesa-rodriguez-de-la-rua\">Dr. Marta Devesa<\/a>\u00a0vom Programm zum Erhalt der Fruchtbarkeit bei Dexeus Mujer gebeten, mit uns \u00fcber dieses Thema zu sprechen.<\/p>\n<p><strong>1. Gibt es eine Altersgrenze?<\/strong><br \/>\nEs gibt keine gesetzlich festgelegte Grenze, es wird jedoch empfohlen, es vor dem 37. Lebensjahr durchzuf\u00fchren, da die Qualit\u00e4t der Eizellen ab diesem Alter abnimmt. Das bedeutet nicht, dass man die Eizellen zwischen 37 und 39 Jahren nicht einfrieren kann, man sollte sich allerdings im jeweiligen Fall \u00fcber die Chancen bewusst sein. Lassen Sie dazu Ihre Eierstockreserve untersuchen. Anhand einer Ultraschalluntersuchung und einer Hormonanalyse l\u00e4sst sie sich ermitteln.<\/p>\n<p><strong>2. Was kostet das?<\/strong><br \/>\nIm Allgemeinen zwischen 2.000 und 3.000 \u20ac. Dar\u00fcber hinaus ist eine j\u00e4hrliche \u201ePauschale\u201d von etwa 300 \u20ac f\u00fcr die Aufbewahrung zu zahlen. In einigen Zentren ist die Pauschale f\u00fcr die ersten Jahre allerdings in den Kosten enthalten. Fragen Sie immer nach, was enthalten ist.<\/p>\n<p><strong>3. Weshalb sollte ich das machen?<\/strong><br \/>\nDas k\u00f6nnte medizinische Gr\u00fcnde haben, aufgrund eines gesundheitlichen Problems, das sich auf die Fruchtbarkeit auswirkt, wie etwa bei einigen Krebsarten. Die meisten Frauen tun dies jedoch, damit sie eine Eizellenreserve mit guter Qualit\u00e4t haben, was ihre Chancen erh\u00f6ht, in der Zukunft schwanger zu werden, da sie keinen festen Partner haben oder der Meinung sind, dass der richtige Moment noch nicht gekommen ist.<\/p>\n<p><strong>4. Kann sich das negativ auf meine Gesundheit auswirken?<\/strong><br \/>\nDas hat keinerlei Auswirkung auf Ihre Gesundheit oder Ihre Fruchtbarkeit. Es kann jedoch zu einigen Komplikationen kommen, etwa zu Beschwerden w\u00e4hrend der Stimulationsbehandlung oder einer Infektion nach der Punktion.<\/p>\n<p><strong>5. Ist eine Mindestzahl an Eizellen erforderlich, um sie einzufrieren?<\/strong><br \/>\nBei der Stimulation k\u00f6nnen zwischen 10 und 20 Eizellen pro Menstruationszyklus gewonnen werden. Dies wird als optimale Menge erachtet. Im Allgemeinen geht man davon aus, dass eine Menge von 10 ausreichend ist, diese Zahl ist jedoch abh\u00e4ngig von Ihrem Alter. Je \u00e4lter Sie sind, desto mehr Eizellen sollten eingefroren werden, da m\u00f6glicherweise die Qualit\u00e4t niedriger ist.<\/p>\n<p><strong>6. Welche Erfolgsraten bieten eingefrorene Eizellen?<\/strong><br \/>\nIm Allgemeinen liegt die Schwangerschaftsrate bei einem Embryonentransfer unter Verwendung von eingefrorenen Eizellen bei 30-50 % pro Zyklus. Die Ergebnisse k\u00f6nnen jedoch je nach angewendeter Technik, der Qualit\u00e4t der Eizellen, dem Alter der Patientin zum Zeitpunkt der Aufbewahrung und den konkreten Merkmalen des jeweiligen Falles variieren.<\/p>\n<p><strong>7. Gibt es ein \u201eVerfallsdatum\u201d?<\/strong><br \/>\nIm Prinzip k\u00f6nnen die Eizellen auf unbestimmte Zeit aufbewahrt werden.<\/p>\n<p><strong>8. Was passiert mit den Eizellen, die nicht verwendet werden?<\/strong><br \/>\nVor Beginn der Behandlung m\u00fcssen Sie diverse Dokumente unterschreiben, in denen erkl\u00e4rt wird, welche Optionen es gibt. Wenn Sie sie nicht verwenden, k\u00f6nnen Sie entscheiden, ob Sie sie vernichten lassen, einer anderen Frau spenden (dies ist nur m\u00f6glich, wenn Sie zum Zeitpunkt der Vitrifikation unter 35 Jahre alt sind) oder f\u00fcr Forschungsprojekte zu medizinischen Zwecken freigeben m\u00f6chten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was Sie wissen m\u00fcssen, bevor Sie Ihre Eizellen einfrieren lassen Obwohl immer mehr Frauen ihre Eizellen einfrieren lassen, wird dar\u00fcber kaum gesprochen und es gibt wenige Informationen dar\u00fcber. Auch die \u00c4rzte schlagen das nicht offen vor, weil sie der Meinung sind, dass dies ein pers\u00f6nliche Entscheidung ist. Deshalb haben wir\u00a0Dr. Marta Devesa\u00a0vom Programm zum Erhalt [&hellip;]<\/p>\n","protected":false},"author":122,"featured_media":4176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1122,1126],"tags":[1206,1181,1180,1205,1204],"class_list":["post-4175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-fruchtbarkeit","tag-einfrieren-von-eizellen","tag-fertilitaet","tag-fruchtbarkeit","tag-kryokonservierung-von-eizellen","tag-preservation-de","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/4175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/users\/122"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=4175"}],"version-history":[{"count":2,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/4175\/revisions"}],"predecessor-version":[{"id":4178,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/4175\/revisions\/4178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/media\/4176"}],"wp:attachment":[{"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=4175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=4175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=4175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}