{"id":512414,"date":"2021-10-06T08:00:00","date_gmt":"2021-10-06T06:00:00","guid":{"rendered":"https:\/\/www.dexeus.com\/blog\/aktuell\/se-pueden-rejuvenecer-lo-ovulos\/"},"modified":"2021-11-10T15:57:57","modified_gmt":"2021-11-10T14:57:57","slug":"konnen-eizellen-verjungt-werden","status":"publish","type":"post","link":"https:\/\/www.dexeus.com\/blog\/de\/aktuell\/konnen-eizellen-verjungt-werden\/","title":{"rendered":"K\u00f6nnen Eizellen verj\u00fcngt werden?"},"content":{"rendered":"\n<p>Wir wissen, dass der Lauf der Zeit unsere Eizellen beeinflusst. Jahr f\u00fcr Jahr nimmt ihre Anzahl und Qualit\u00e4t ab. Es ist ein nat\u00fcrlicher Prozess, der sich nach dem 35. Lebensjahr beschleunigt. Die Mechanismen, die hinter diesem Prozess stehen, sind jedoch noch nicht vollst\u00e4ndig gekl\u00e4rt.<\/p>\n\n\n\n<p>Die Tatsache, dass manche Frauen fr\u00fcher in die Wechseljahre kommen als andere oder dass ihre Eierstockreserve geringer ist, deutet jedoch darauf hin, dass es individuelle genetische Faktoren gibt, die einen Einfluss haben k\u00f6nnen. Aus diesem Grund versuchen einige Forscher, neue Hinweise zu finden, indem sie genetische Ver\u00e4nderungen untersuchen, die bei der Beschleunigung oder Verz\u00f6gerung dieses Prozesses eine Rolle spielen k\u00f6nnten. Andere versuchen herauszufinden, ob es m\u00f6glich ist, den Beginn der Menopause vorauszusagen, oder untersuchen, wie man die Qualit\u00e4t der Eizellen durch verschiedene Strategien verbessern kann.<\/p>\n\n\n\n<p>Es handelt sich dabei um sehr aktuelle Forschungsstudien, bisher hat jedoch noch keine von ihnen schl\u00fcssige Ergebnisse geliefert. Sie alle geben jedoch Anlass zur Hoffnung und zur Entwicklung neuer Behandlungen, um die Fruchtbarkeit zu verl\u00e4ngern oder ihren R\u00fcckgang zu verhindern, insbesondere bei jungen Frauen.<\/p>\n\n\n\n<p>In diesem Beitrag fasst <a href=\"https:\/\/de.dexeus.com\/uber-uns\/unsere-zentren\/medizinisches-team\/nikolaos-polyzos\" target=\"_blank\" rel=\"noreferrer noopener\">Dr. Nikolaos Polyzos<\/a>, Leiter der Abteilung f\u00fcr Reproduktionsmedizin in Dexeus Mujer, einige der wichtigsten aktuellen Forschungsrichtungen auf diesem Gebiet zusammen:<\/p>\n\n\n\n<ul><li><strong><strong>Versuche mit Stammzellen.<\/strong> <\/strong>Stammzellen zeichnen sich durch ihre F\u00e4higkeit aus, sich weiter zu entwickeln und sich in andere Zelltypen umzuwandeln. In vielen Studien wird mit Stammzellen gearbeitet, um krankes oder gesch\u00e4digtes Gewebe zu regenerieren und zu reparieren. Im Bereich der Fortpflanzung ist das Ziel, solche Zellen zur Durchf\u00fchrung von Eierstockfunktionen zu bef\u00e4higen, die bisherigen Versuche sind jedoch &#8211; gemessen an der Zahl der untersuchten Patientinnen &#8211; klein und liefern noch keine eindeutigen Ergebnisse.<\/li><li><strong><strong>Testosteron-Behandlungen.<\/strong> <\/strong>Es ist erwiesen, dass der Testosteronspiegel im Blut mit zunehmendem Alter deutlich abnimmt. Es wird daher vermutet, dass dieses Hormon eine wichtige Rolle bei der reproduktiven Alterung spielen k\u00f6nnte. In diesem Bereich wurden mehrere Studien durchgef\u00fchrt, bei denen eine zus\u00e4tzliche Dosis dieses Hormons verabreicht wurde, aber die Divergenzen bez\u00fcglich der Dauer und der verabreichten Dosen haben endg\u00fcltige Ergebnisse verhindert. In diesem Sinne hat Dexeus Mujer eine multizentrische klinische Studie mit der Bezeichnung TTRANSPORT (Testosterone TRANSdermal gel for Poor Ovarian Responders Trial) gestartet, mit der untersucht werden soll, ob die Verabreichung von Testosteron vor Beginn der Stimulation der Eierst\u00f6cke durch Auftragen eines Gels auf die Haut die Reaktion von Frauen mit geringer Eierstockreserve verbessern kann. Vorl\u00e4ufige Ergebnisse dieser Studie werden voraussichtlich im Jahr 2022 vorliegen.<\/li><li><strong><em><strong><em>Germline nuclear transfer<\/em> (Keimbahn-Zellkerntransfer).<\/strong><\/em><\/strong> Hierbei handelt es sich noch um einen experimentellen Forschungszweig. Das Verfahren besteht darin, den Zellkern &#8211; der die genetische Information enth\u00e4lt &#8211; aus der Eizelle einer \u00e4lteren Frau in das Zytoplasma der Eizelle einer jungen Spenderin einzubringen, der zuvor der Zellkern entnommen wurde, um sie zu Fortpflanzungszwecken zu verwenden. Diese Technik ist nicht in allen L\u00e4ndern rechtlich zugelassen und auch ethisch umstritten, daher wird sie derzeit noch gepr\u00fcft und weiterentwickelt.<\/li><li><strong><strong>Wachstumsfaktoren.<\/strong> <\/strong>Wachstumsfaktoren beeinflussen zahlreiche biologische Prozesse, die die Zellentwicklung und deren Regeneration f\u00f6rdern. Sie werden in verschiedenen medizinischen Fachbereichen eingesetzt und die Ergebnisse sind in zahlreichen Studien und wissenschaftlichen Ver\u00f6ffentlichungen belegt worden. Die Technik besteht darin, aus einer Probe des eigenen Blutes der Patientin Proteine und andere Molek\u00fcle mit biologischer Aktivit\u00e4t zu entnehmen, die die Gewebeerneuerung beschleunigen. Bei der assistierten Reproduktion sind sie zur Erh\u00f6hung der Empf\u00e4nglichkeit der Geb\u00e4rmutterschleimhaut bei Frauen eingesetzt worden, die keine ausreichende Dicke f\u00fcr den Embryotransfer erreicht haben. Derzeit laufen Studien, um zu pr\u00fcfen, ob es die Reaktion der Eierst\u00f6cke bei Patientinnen mit geringer Ovarialreserve verbessern kann. Es liegen noch keine Ergebnisse vor, aber es k\u00f6nnte eine vielversprechende Behandlung sein.<\/li><\/ul>\n\n\n\n<p>Es gibt somit viele offene Forschungslinien. Es ist daher gut m\u00f6glich, dass in den n\u00e4chsten Jahren weitaus mehr Fortschritte gemacht werden als wir uns derzeit vorstellen k\u00f6nnen. Wir k\u00f6nnen jedoch nicht gegen die Natur k\u00e4mpfen: die Genetik bestimmt, wann die Menopause bei jeder einzelnen Frau beginnt. Au\u00dferdem steht die Qualit\u00e4t der Eizellen in direktem Zusammenhang mit dem Alter der Mutter. Experten empfehlen daher allen Frauen, ihre Eierstockreserve untersuchen zu lassen und, falls sie die Mutterschaft aufschieben m\u00fcssen, ihre Eizellen vor dem Alter von 35 Jahren einzufrieren, um ihre Fruchtbarkeit zu erhalten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir wissen, dass der Lauf der Zeit unsere Eizellen beeinflusst. Jahr f\u00fcr Jahr nimmt ihre Anzahl und Qualit\u00e4t ab. Es ist ein nat\u00fcrlicher Prozess, der sich nach dem 35. Lebensjahr beschleunigt. Die Mechanismen, die hinter diesem Prozess stehen, sind jedoch noch nicht vollst\u00e4ndig gekl\u00e4rt. Die Tatsache, dass manche Frauen fr\u00fcher in die Wechseljahre kommen als [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":499453,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1122,1126],"tags":[1149,1249,1180,2503,2501,1364,1365,2502],"_links":{"self":[{"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/512414"}],"collection":[{"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=512414"}],"version-history":[{"count":2,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/512414\/revisions"}],"predecessor-version":[{"id":512421,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/posts\/512414\/revisions\/512421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/media\/499453"}],"wp:attachment":[{"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=512414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=512414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=512414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}