{"id":4015,"date":"2018-01-24T08:00:14","date_gmt":"2018-01-24T06:00:14","guid":{"rendered":"https:\/\/www.dexeus.com\/blog\/actualite\/entrevista-dr-nikolaos-polyzos\/"},"modified":"2019-06-04T12:52:15","modified_gmt":"2019-06-04T10:52:15","slug":"entretien-dr-nikolaos-polyzos","status":"publish","type":"post","link":"https:\/\/www.dexeus.com\/blog\/fr\/actualite\/entretien-dr-nikolaos-polyzos\/","title":{"rendered":"Entretien avec le Dr Nikolaos Polyzos \u00ab Nous cherchons des solutions pour les cas difficiles \u00bb"},"content":{"rendered":"<div id=\"attachment_4026\" style=\"width: 203px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4026\" class=\"wp-image-4026 size-full\" src=\"https:\/\/www.dexeus.com\/blog\/wp-content\/uploads\/2018\/01\/nikolaos-polyzos-1.png\" alt=\"Dr. Nikolaos Polyzos Director cl\u00ednico y cient\u00edfico del Servicio de Medicina de la Reproducci\u00f3n de Dexeus Mujer\" width=\"193\" height=\"220\" \/><p id=\"caption-attachment-4026\" class=\"wp-caption-text\"><span lang=\"fr\" tabindex=\"0\">Dr Nikolaos Polyzos directeur clinique et scientifique du Service de m\u00e9decine de la reproduction de Dexeus Mujer<\/span><\/p><\/div>\n<p>Le Dr Nikolaos Polyzos, directeur clinique et scientifique du Service de m\u00e9decine de la reproduction de Dexeus Mujer, traite depuis des ann\u00e9es des patientes \u00e2g\u00e9es dont la r\u00e9serve ovarienne est faible ou qui ne r\u00e9pondent pas bien aux traitements de stimulation hormonale, des circonstances qui rendent particuli\u00e8rement difficile l&rsquo;obtention d&rsquo;une grossesse. Son message pour toutes ces patientes est qu&rsquo;elles ne doivent pas perdre l&rsquo;espoir, car il existe de nombreuses \u00e9tudes en cours dont l&rsquo;objectif est d&rsquo;am\u00e9liorer les r\u00e9sultats actuels.<\/p>\n<p><strong>Qu&rsquo;entend-on par \u00ab r\u00e9serve ovarienne \u00bb ?<\/strong><br \/>\nLes m\u00e9decins emploient ce terme pour d\u00e9signer \u00e0 la fois le nombre de follicules contenus dans les ovaires et la qualit\u00e9 des follicules. En g\u00e9n\u00e9ral, plus une femme est jeune meilleure est la qualit\u00e9 de ses ovules.<\/p>\n<p><strong>Quand consid\u00e8re-t-on qu&rsquo;une femme a une \u00ab faible r\u00e9serve ovarienne \u00bb ?<\/strong><br \/>\nUn nombre \u00e9gal ou inf\u00e9rieur \u00e0 quatre ovocytes par ovaire ou de sept en tout (en additionnant ceux des deux ovaires) et de faibles taux d&rsquo;hormone antimull\u00ebrienne (AMH) constituent deux indicateurs d&rsquo;une faible r\u00e9serve.<\/p>\n<p><strong>Quel pourcentage de femmes pr\u00e9sente ce probl\u00e8me ?<\/strong><br \/>\nIl n&rsquo;est pas tr\u00e8s \u00e9lev\u00e9, mais il a augment\u00e9 en raison du recul de l&rsquo;\u00e2ge de la maternit\u00e9. Aujourd&rsquo;hui, 25 % environ des patientes d&rsquo;assistance m\u00e9dicale \u00e0 la procr\u00e9ation ont une faible r\u00e9serve ovarienne.<\/p>\n<p><strong>Comment cela affecte-t-il vos chances de tomber enceinte ?<\/strong><br \/>\nLe fait d&rsquo;avoir peu d&rsquo;ovocytes ne signifie pas que nous ne puissions pas obtenir des ovules de qualit\u00e9. Cependant, lorsqu&rsquo;il y en a moins, les chances d&rsquo;obtenir des embryons viables sont plus r\u00e9duites ; si vous ajoutez \u00e0 cela un \u00e2ge avanc\u00e9, le risque que certains d&rsquo;entre eux pr\u00e9sentent des anomalies chromosomiques est aussi plus \u00e9lev\u00e9.<\/p>\n<p><strong>Mais les traitements hormonaux augmentent le nombre d&rsquo;ovocytes, n&rsquo;est-ce pas ?<\/strong><br \/>\nOui. Cela dit, tout le monde ne r\u00e9pond pas de la m\u00eame fa\u00e7on, et les femmes dont la r\u00e9serve ovarienne est faible ont g\u00e9n\u00e9ralement une faible r\u00e9ponse \u00e0 ces traitements.<\/p>\n<p><strong>Quelles sont les options disponibles dans ces cas-l\u00e0 ?<\/strong><br \/>\nLes m\u00e9decins conseillent d&rsquo;effectuer plus d&rsquo;un cycle de stimulation, car il a \u00e9t\u00e9 d\u00e9montr\u00e9 que le cumul d&rsquo;ovocytes ou d&#8217;embryons peut augmenter le taux de grossesse, bien que les r\u00e9sultats d\u00e9pendent de chaque cas et de l&rsquo;\u00e2ge de chaque patiente.<\/p>\n<p><strong>Et comment pourrait-on am\u00e9liorer les r\u00e9sultats ?<\/strong><br \/>\nActuellement, je m\u00e8ne un essai clinique auquel participent des experts d&rsquo;Europe, d&rsquo;Australie et d&rsquo;Asie portant sur l&rsquo;\u00e9tude d&rsquo;un traitement m\u00e9dical \u00e0 base de testost\u00e9rone visant \u00e0 am\u00e9liorer la r\u00e9ceptivit\u00e9 des ovaires \u00e0 la stimulation hormonale. D&rsquo;autres \u00e9tudes analysent les causes g\u00e9n\u00e9tiques susceptibles de favoriser une faible r\u00e9ponse ovarienne, la mani\u00e8re d&rsquo;activer les quelques ovocytes restants dans l&rsquo;ovaire ou la mani\u00e8re de d\u00e9velopper des ovules \u00e0 partir de cellules souches. Il est encore trop t\u00f4t pour donner des r\u00e9sultats, mais la recherche est essentielle pour continuer \u00e0 progresser.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Dr Nikolaos Polyzos, directeur clinique et scientifique du Service de m\u00e9decine de la reproduction de Dexeus Mujer, traite depuis des ann\u00e9es des patientes \u00e2g\u00e9es dont la r\u00e9serve ovarienne est faible ou qui ne r\u00e9pondent pas bien aux traitements de stimulation hormonale, des circonstances qui rendent particuli\u00e8rement difficile l&rsquo;obtention d&rsquo;une grossesse. Son message pour toutes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[534,574],"tags":[1093,835,764,1021,805,817,836,837,840,841,838,1094,839,850,842],"_links":{"self":[{"href":"https:\/\/www.dexeus.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/4015"}],"collection":[{"href":"https:\/\/www.dexeus.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dexeus.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=4015"}],"version-history":[{"count":5,"href":"https:\/\/www.dexeus.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/4015\/revisions"}],"predecessor-version":[{"id":4035,"href":"https:\/\/www.dexeus.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/4015\/revisions\/4035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/fr\/wp-json\/wp\/v2\/media\/3219"}],"wp:attachment":[{"href":"https:\/\/www.dexeus.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=4015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=4015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=4015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}