{"id":4581,"date":"2019-04-24T08:00:49","date_gmt":"2019-04-24T06:00:49","guid":{"rendered":"https:\/\/www.dexeus.com\/blog\/attualita\/niedrige-ovarielle-reserve-10-eckdaten-die-sie-interessieren-sollten\/"},"modified":"2019-05-20T12:58:50","modified_gmt":"2019-05-20T10:58:50","slug":"scarsa-riserva-ovarica-10-dati-che-ti-interessano","status":"publish","type":"post","link":"https:\/\/www.dexeus.com\/blog\/it\/attualita\/scarsa-riserva-ovarica-10-dati-che-ti-interessano\/","title":{"rendered":"Scarsa riserva ovarica: 10 dati che ti interessano"},"content":{"rendered":"<p>Se stai cercando di rimanere incinta e ti hanno diagnosticato una scarsa riserva ovarica, probabilmente immaginerai che qualcosa non va bene. Ma non ti allarmare. Si tratta di un problema sempre pi\u00f9 frequente, a causa del ritardo della maternit\u00e0. E s\u00ec, riguarda la fertilit\u00e0, perch\u00e9 indica che il numero di ovuli che potenzialmente possono maturare ed essere fecondati \u00e8 al di sotto del livello ritenuto &#8220;normale&#8221;. Questo, per\u00f2, non significa che non puoi essere madre. In questo post, il <a href=\"http:\/\/it.dexeus.com\/a-proposito-di-dexeus\/quadro-medico\/nikolaos-polyzos\"><strong>Dr. Nikolaos Polyzos<\/strong><\/a>, che lavora nel nostro centro ed \u00e8 uno dei migliori esperti europei in questo tema, risponde a 10 dubbi frequenti.<\/p>\n<ol>\n<li><strong> Qual \u00e8 la causa? <\/strong>L&#8217;et\u00e0 della donna \u00e8 determinante e il rapporto \u00e8 inversamente proporzionale: a maggiore et\u00e0, minore riserva ovarica. Ma questo problema pu\u00f2 riguardare anche giovani donne, come avviene nei casi di insufficienza ovarica precoce. Altre possibili cause sono: trattamenti medici o chirurgici, chemioterapia, inquinamento ambientale, abitudini di vita poco sane e alcune malattie, come l&#8217;endometriosi.<\/li>\n<li><strong> Come si rileva? <\/strong>Si pu\u00f2 accertare facilmente. Basta fare un\u2019ecografia transvaginale tra il terzo e il quinto giorno del ciclo mestruale per fare un conteggio dei follicoli contenuti in ogni ovaio, e un&#8217;analisi del sangue, per conoscere i valori di diversi ormoni: l&#8217;ormone follicolo-stimolante (FSH), che libera l&#8217;ipofisi e si occupa di attivare le ovaie, l\u2019ormone antim\u00fclleriano (AMH), che rilascia il follicolo ovarico l\u2019estradiolo. Questi ultimi due sono legati al processo di sviluppo degli ovuli. Un valore alto del primo (FSH) indica una bassa riserva ovarica, dato che il suo valore aumenta in presenza di pochi ovociti. E, al contrario, un valore alto dell\u2019AMH e dell&#8217; estradiolo, in generale, indicano una buona riserva ovarica, dato che \u00e8 un segnale della presenza di molti ovuli in processo di maturazione.<\/li>\n<li><strong> Che cosa si ritiene una scarsa riserva ovarica? <\/strong>In generale, un conteggio uguale o inferiore a 4 ovociti per ovaio, o di 7 in totale (sommando quelli di entrambe le ovaie) e livelli bassi dell&#8217;ormone AMH sono indicatori di una scarsa riserva ovarica.<\/li>\n<li><strong> Quanto incide sulla fertilit\u00e0? <\/strong>Le possibilit\u00e0 di restare incinta utilizzando i propri ovociti si riducono, ma ci\u00f2 che pi\u00f9 incide alla fine \u00e8 l&#8217;et\u00e0. Se hai una bassa riserva ovarica, ma meno di 35 anni, le tue possibilit\u00e0 sono maggiori che se ne avessi pi\u00f9 di 40. Per questo motivo, sebbene ancora non stai pensando di diventare madre, e hai solo 30 anni o meno, chiedi al tuo ginecologo che ti faccia una valutazione, al fine di poter pianificare meglio la maternit\u00e0.<\/li>\n<li><strong> Se sono giovane ma ancora non voglio essere madre dovrei preservare? <\/strong>\u00c8 qualcosa che devi valutare con il tuo ginecologo. Ma \u00e8 una scelta che, in ogni caso, non bisogna mai escludere a priori, gi\u00e0 che essere giovane \u00e8 un vantaggio, perch\u00e9 i tuoi ovuli sono di maggiore qualit\u00e0.<\/li>\n<li><strong> \u00c8 normale avere una scarsa riserva ovarica ai 40 anni? <\/strong>\u00c8 normale che diminuisca la riserva ovarica, ma non tutte le donne di 40 anni hanno una &#8220;scarsa riserva ovarica&#8221;. Per questo ogni caso deve essere studiato sempre individualmente.<\/li>\n<li><strong> Se voglio essere madre e ho questo problema, devo necessariamente rivolgermi alla riproduzione assistita? <\/strong>Dipende dall&#8217;et\u00e0 che hai e la causa che lo ha provocato. Se il motivo \u00e8 un\u2019insufficienza ovarica precoce o un trattamento di chemioterapia, s\u00ec, perch\u00e9 \u00e8 l&#8217;unica opzione in questi casi ed \u00e8 probabile che, se non hai preservato, sia necessario ricorrere all\u2019ovodonazione. Se il problema \u00e8 dovuto alla tua et\u00e0, chiedi al tuo ginecologo di indicarti quali opzioni hai a disposizione e, a partire da queste, decidi insieme a lui quale possa essere la migliore per te.<\/li>\n<li><strong> Avere una scarsa riserva ovarica diminuisce anche il tasso di gravidanza in FIV? <\/strong>Non necessariamente. In generale, si tende a ottenere un minor numero di ovociti e di embrioni vitali, ma vi sono donne con bassa riserva ovarica che rispondono bene ai trattamenti di stimolazione ormonale e offrono ovuli di buona qualit\u00e0. Il problema aggiunto, come sempre, \u00e8 l&#8217;et\u00e0, perch\u00e9 se la madre ha un&#8217;et\u00e0 avanzata, i suoi ovuli sono di peggiore qualit\u00e0 e vi \u00e8 anche un maggior rischio di alterazioni cromosomiche e di fallimento di impianto.<\/li>\n<li><strong> \u00c8 consigliabile effettuare vari cicli di stimolazione ovarica in questi casi? <\/strong>Attualmente non esiste alcun trattamento che migliori la riserva ovarica. Si stanno studiando, ma per il momento sono ancora sperimentali. I trattamenti di stimolazione ormonale hanno come obiettivo quello di aumentare il numero di ovociti che possiamo ottenere, ma non tutte le donne rispondono allo stesso modo. Per questo motivo, bisogna valutare ogni singolo caso.<\/li>\n<li><strong> Quando \u00e8 indicato optare per la donazione di ovociti? <\/strong>Quando le ovaie non producono ovuli vitali o gli ovuli che si ottengono non soddisfano la qualit\u00e0 sufficiente per poter essere fecondati e portare a termine una gravidanza. Il vantaggio dell\u2019ovodonazione \u00e8 che aumenta considerevolmente le possibilit\u00e0 di raggiungere una gestazione rispetto all&#8217;uso dei propri ovociti, sebbene la madre abbia gi\u00e0 compiuto i 40 anni: attualmente il tasso di gravidanza con ovodonazione si aggira attorno al 60% rispetto al 30% che offre una FIV con ovociti propri.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Se stai cercando di rimanere incinta e ti hanno diagnosticato una scarsa riserva ovarica, probabilmente immaginerai che qualcosa non va bene. Ma non ti allarmare. Si tratta di un problema sempre pi\u00f9 frequente, a causa del ritardo della maternit\u00e0. E s\u00ec, riguarda la fertilit\u00e0, perch\u00e9 indica che il numero di ovuli che potenzialmente possono maturare [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[536,562],"tags":[566,668,675,1372,652],"_links":{"self":[{"href":"https:\/\/www.dexeus.com\/blog\/it\/wp-json\/wp\/v2\/posts\/4581"}],"collection":[{"href":"https:\/\/www.dexeus.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dexeus.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=4581"}],"version-history":[{"count":2,"href":"https:\/\/www.dexeus.com\/blog\/it\/wp-json\/wp\/v2\/posts\/4581\/revisions"}],"predecessor-version":[{"id":4583,"href":"https:\/\/www.dexeus.com\/blog\/it\/wp-json\/wp\/v2\/posts\/4581\/revisions\/4583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/it\/wp-json\/wp\/v2\/media\/4344"}],"wp:attachment":[{"href":"https:\/\/www.dexeus.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=4581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=4581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=4581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}