{"id":4276,"date":"2019-04-10T08:00:55","date_gmt":"2019-04-10T06:00:55","guid":{"rendered":"https:\/\/www.dexeus.com\/blog\/?p=4276"},"modified":"2023-09-18T13:31:38","modified_gmt":"2023-09-18T11:31:38","slug":"sabes-que-es-el-sindrome-del-ovario-poliquistico","status":"publish","type":"post","link":"https:\/\/www.dexeus.com\/blog\/actualidad\/sabes-que-es-el-sindrome-del-ovario-poliquistico\/","title":{"rendered":"\u00bfSabes qu\u00e9 es el S\u00edndrome del Ovario Poliqu\u00edstico?"},"content":{"rendered":"\n<p>\u00a1Seguro que no es la primera vez que oyes esta expresi\u00f3n! Pero \u00bfsabes exactamente qu\u00e9 significa tener <strong>ovarios poliqu\u00edsticos<\/strong>?&nbsp; Si la respuesta es no, \u00a1tranquila!, porque existe mucha confusi\u00f3n respecto a este t\u00e9rmino. De entrada, parece indicar la presencia de m\u00faltiples quistes en el ovario. Pero no es as\u00ed. Los m\u00e9dicos la utilizan cuando detectan un gran n\u00famero de fol\u00edculos en los ovarios. Pero los fol\u00edculos no son quistes, sino unas estructuras que contienen \u00f3vulos que todav\u00eda no han madurado. Este hecho es frecuente en mujeres j\u00f3venes y, en principio, no debe ser un motivo de preocupaci\u00f3n.<\/p>\n\n\n\n<p>Pero hay que estar atenta, ya que un ovario de aspecto poliqu\u00edstico tambi\u00e9n puede ser un s\u00edntoma indicativo de una disfunci\u00f3n ov\u00e1rica que se conoce por el nombre del <strong>S\u00edndrome del Ovario Poliqu\u00edstico (SOP)<\/strong>. Este s\u00edndrome requiere atenci\u00f3n m\u00e9dica, ya que puede afectar a la capacidad reproductiva y favorecer el desarrollo de alteraciones metab\u00f3licas, como diabetes u obesidad. Por este motivo, Dexeus Mujer ha creado una <a href=\"https:\/\/www.dexeus.com\/problemas-ginecologicos\/sindrome-ovario-poliquistico\" target=\"_blank\" rel=\"noopener\"><strong><u>Unidad espec\u00edfica<\/u><\/strong><\/a>, cuyo objetivo es abordar este problema desde un punto de vista multidisciplinario.<\/p>\n\n\n\n<p>En este post te explicamos c\u00f3mo se puede mantener este problema bajo control<em>.<\/em><\/p>\n\n\n\n<p><strong>\u00bfEn qu\u00e9 consiste, exactamente, el SOP y a cu\u00e1ntas mujeres afecta? <\/strong><\/p>\n\n\n\n<p>Se trata de una disfunci\u00f3n ov\u00e1rica que puede provocar alteraciones a nivel hormonal y metab\u00f3lico. La causa no se conoce exactamente, aunque se cree que puede haber una cierta predisposici\u00f3n gen\u00e9tica. En total, se calcula que afecta a entre un 8 y un 13% de la poblaci\u00f3n femenina. Pero muchas de las mujeres que lo tienen, no lo saben.<br>\n\u00bfPor qu\u00e9?&nbsp;Porque se trata de un problema de salud que est\u00e1 infradiagnosticado, ya que la forma en la que puede manifestarse es muy variada y a veces es dif\u00edcil hacer un diagn\u00f3stico temprano. Es lo que ocurre con las adolescentes. Se considera que durante los primeros ocho a\u00f1os desde que te viene la regla pueden darse algunas irregularidades en la menstruaci\u00f3n y es frecuente tener acn\u00e9, por lo que hay que dar un cierto margen de tiempo antes de empezar a poner \u2018etiquetas\u2019.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 s\u00edntomas puede provocar?<\/strong><\/p>\n\n\n\n<p>Var\u00edan mucho de una mujer a otra. Los m\u00e1s frecuentes son acn\u00e9, falta de reglas o reglas irregulares e hirsutismo. Tambi\u00e9n se caracteriza por un \u00edndice de masa corporal (IMC) alto, tendencia a ganar peso y ovarios de aspecto poliqu\u00edstico. Pero el hecho de tener ovarios de aspecto poliqu\u00edstico no quiere decir que la causa sea el SOP, puede significar simplemente que tienen una buena reserva ov\u00e1rica. Por ello, los m\u00e9dicos deber\u00edan utilizar esta expresi\u00f3n con cierta precauci\u00f3n, ya que puede crear confusi\u00f3n.<\/p>\n\n\n\n<p><strong>Y \u00bfc\u00f3mo se determina entonces, si se padece o no el s\u00edndrome?<\/strong><\/p>\n\n\n\n<p>Para poder confirmar el diagn\u00f3stico es necesario que se den al menos dos de estas tres condiciones:<\/p>\n\n\n\n<ol>\n<li>Tener ovarios de aspecto poliqu\u00edstico<\/li>\n\n\n\n<li>Un nivel en sangre de andr\u00f3genos (hormonas masculinas) m\u00e1s elevado de lo que se considera normal o ciertos rasgos f\u00edsicos que sean indicativos de ese exceso de andr\u00f3genos (hirsutismo, acn\u00e9\u2026).<\/li>\n\n\n\n<li>Falta de regla por anovulaci\u00f3n, o reglas poco frecuentes e irregulares.<\/li>\n<\/ol>\n\n\n\n<p><strong>\u00bfPor qu\u00e9 Dexeus Mujer ha decidido crear una Unidad espec\u00edfica para tratar este s\u00edndrome?<\/strong><\/p>\n\n\n\n<p>Porque el SOP es un problema que merece una mayor atenci\u00f3n m\u00e9dica de la que hasta ahora se le ha dado y un abordaje que incluya cambios espec\u00edficos en el estilo de vida (nutrici\u00f3n, ejercicio, etc.), ya que se ha demostrado que esos cambios contribuyen a mejorar el s\u00edndrome y a prevenir el desarrollo de otros problemas de salud que, a la larga, puede provocar.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 tipo de problemas?<\/strong><\/p>\n\n\n\n<p>El SOP se asocia a una resistencia a la insulina, por lo que puede favorecer el desarrollo de diabetes y obesidad. Por eso es muy importante que el control y seguimiento m\u00e9dico de este s\u00edndrome se haga desde un punto de vista multidisciplinario, que incluya a expertos en ginecolog\u00eda, endocrinolog\u00eda y nutrici\u00f3n. Tambi\u00e9n se asocia a un mayor riesgo de trastornos de salud cardiovascular y, en algunos casos, puede comportar problemas de fertilidad, por lo que puede ser necesaria la intervenci\u00f3n de un experto en medicina de la reproducci\u00f3n.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 porcentaje de mujeres con SOP tienen problemas de fertilidad?<\/strong><\/p>\n\n\n\n<p>Por mi experiencia, puedo decir que un 50% de las pacientes que visito tiene alg\u00fan problema que podr\u00eda estar relacionado con esta patolog\u00eda (irregularidades menstruales, hirsutismo, acn\u00e9\u2026), y, de estas, la mitad, aproximadamente, son pacientes que no logran quedarse embarazadas.<\/p>\n\n\n\n<p><strong>Y qu\u00e9 soluci\u00f3n hay en estos casos \u00bfes necesario recurrir a t\u00e9cnicas de reproducci\u00f3n asistida?<\/strong><\/p>\n\n\n\n<p>Hay que estudiar cada caso. Si se trata de un problema de anovulaci\u00f3n y no hay otros factores de esterilidad (fallo tub\u00e1rico o un factor masculino) puede estar indicado realizar un tratamiento hormonal para inducir la ovulaci\u00f3n. Y, en funci\u00f3n de los resultados, decidir si es necesario o no recurrir a una fecundaci\u00f3n in vitro.<\/p>\n\n\n\n<p><strong>De forma m\u00e1s global, \u00bfqu\u00e9 tratamientos hay para la enfermedad?&nbsp;<\/strong><\/p>\n\n\n\n<p>El tratamiento siempre ha de ser individualizado. En general, la primera opci\u00f3n es intentar controlar el s\u00edndrome mediante la introducci\u00f3n de una serie de pautas en el estilo de vida (control del peso, pr\u00e1ctica regular de ejercicio, reducci\u00f3n de la ingesta de az\u00facar, etc.) Muchas veces, esas medidas y un seguimiento de control m\u00e9dico regular bastan. Si no mejora, entonces puede estar indicado el tratamiento farmacol\u00f3gico.<\/p>\n\n\n\n<p><strong>\u00bfTe refieres a tomar anticonceptivos\u2026?<\/strong><\/p>\n\n\n\n<p>Depende. En algunos casos, la toma de anticonceptivos puede ayudar a disminuir o eliminar el acn\u00e9 y el hirsutismo. Sin embargo, no curan el s\u00edndrome, y, de hecho, pueden enmascararlo, ya que algunas mujeres se dan cuenta de que lo tienen cuando dejan de tomar los anticonceptivos porque quieren quedarse embarazadas y comprueban que no les viene la regla o empiezan a tener acn\u00e9 o vello. De todos modos, la toma de anticonceptivos puede tener un efecto beneficioso, ya que la falta de reglas que provoca el SOP puede favorecer el desarrollo de un c\u00e1ncer de endometrio a largo plazo, y con la toma de anticonceptivos ese riesgo disminuye.<\/p>\n\n\n\n<p><strong>\u00bfEl embarazo puede provocar cambios favorables?<\/strong><\/p>\n\n\n\n<p>No es un factor determinante. Pero a lo largo de la vida es posible que los s\u00edntomas cambien y con la edad se pueden suavizar.<\/p>\n\n\n\n<p><strong>\u00bfEntonces, el SOP mejora con la menopausia?&nbsp;<\/strong>Algunos s\u00edntomas s\u00ed, pero es importante mantener el control, ya que con la menopausia aumenta el riesgo de problemas de salud cardiovascular. De hecho, un 40% de las mujeres mayores de 40 a\u00f1os con SOP presentan lo que se llama un s\u00edndrome metab\u00f3lico que se caracteriza por tener colesterol elevado, hipertensi\u00f3n y un \u00edndice de masa corporal alto, tres factores de riesgo cardiovascular que es necesario mantener bajo control.<\/p>\n\n\n\n<p><strong>O sea, que no podemos relajarnos\u2026<\/strong><\/p>\n\n\n\n<p>No, pero tampoco hay que alarmarse. Con las medidas adecuadas y bajo seguimiento m\u00e9dico, podemos mantener el SOP bajo control y prevenir la aparici\u00f3n de otros problemas de salud. La creaci\u00f3n de esta nueva Unidad responde precisamente a este objetivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Seguro que no es la primera vez que oyes esta expresi\u00f3n! Pero \u00bfsabes exactamente qu\u00e9 significa tener ovarios poliqu\u00edsticos?&nbsp; Si la respuesta es no, \u00a1tranquila!, porque existe mucha confusi\u00f3n respecto a este t\u00e9rmino. De entrada, parece indicar la presencia de m\u00faltiples quistes en el ovario. Pero no es as\u00ed. Los m\u00e9dicos la utilizan cuando detectan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4277,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5,6],"tags":[28,1305,1304,1303,1302],"_links":{"self":[{"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/posts\/4276"}],"collection":[{"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/comments?post=4276"}],"version-history":[{"count":17,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/posts\/4276\/revisions"}],"predecessor-version":[{"id":639163,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/posts\/4276\/revisions\/639163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/media\/4277"}],"wp:attachment":[{"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/media?parent=4276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/categories?post=4276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/tags?post=4276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}