{"id":4540,"date":"2019-05-15T08:00:24","date_gmt":"2019-05-15T06:00:24","guid":{"rendered":"https:\/\/www.dexeus.com\/blog\/?p=4540"},"modified":"2023-08-29T14:27:03","modified_gmt":"2023-08-29T12:27:03","slug":"tener-una-regla-muy-abundante-es-normal","status":"publish","type":"post","link":"https:\/\/www.dexeus.com\/blog\/buenos-habitos\/tener-una-regla-muy-abundante-es-normal\/","title":{"rendered":"Tener una regla muy abundante \u00bfes normal\u2026?"},"content":{"rendered":"<p>La respuesta es no, y las causas pueden ser muchas, pero \u00a1tranquila!, porque en la mayor\u00eda de los casos se debe a un desajuste funcional y suele ser algo temporal. Aunque no por eso hay que pasarlo por alto, ya que un sangrado menstrual excesivo puede indicar la existencia de alg\u00fan problema de salud. Pero vayamos por partes: ante todo, hay que aclarar qu\u00e9 se considera \u201cexcesivo\u201d, ya que siempre existe un punto subjetivo de valoraci\u00f3n personal: todas tenemos la t\u00edpica amiga que necesita cambiarse cada dos horas de tamp\u00f3n o compresa porque dice que tiene mucha cantidad, o tal vez un mes nos baja un poco m\u00e1s, y no por eso hay que asustarse.<\/p>\n<p>Seg\u00fan explica la <a href=\"https:\/\/www.dexeus.com\/quienes-somos\/nuestros-centros\/equipo-medico\/nuria-parera-junyent\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Dra. N\u00faria Parera<\/strong><\/span><\/a>, ginec\u00f3loga de nuestro centro y responsable de la Unidad de Ginecolog\u00eda de la Infancia y la Adolescencia, se considera un sangrado menstrual excesivo aquel que \u201cdura m\u00e1s de 8 d\u00edas, se presenta en intervalos de menos de 20 d\u00edas o hace que empapemos m\u00e1s de 6 compresas o tampones al d\u00eda\u201d. Si usas la copa, depende del tama\u00f1o que tenga esta y tambi\u00e9n de la frecuencia con la que suelas vaciarla. Pero, en general, una p\u00e9rdida de m\u00e1s de 80 ml al d\u00eda es excesiva. De todos modos, a trav\u00e9s de un an\u00e1lisis de sangre se puede valorar si esa p\u00e9rdida es tolerable o no.<\/p>\n<p>En todos los casos, y m\u00e1s si se cumplen dos o m\u00e1s de estas tres situaciones, debes pedir visita con tu ginec\u00f3loga\/o, para que compruebe que todo est\u00e1 bien y pueda hacer una valoraci\u00f3n, ya que hay que descartar la presencia de anemia o la existencia de alg\u00fan problema org\u00e1nico, como puede ser la presencia de un mioma, un p\u00f3lipo endometrial u otras enfermedades ginecol\u00f3gicas o no ginecol\u00f3gicas.<\/p>\n<p>En este post, te indicamos, de forma resumida, cu\u00e1les son las causas m\u00e1s frecuentes y qu\u00e9 tratamientos se suelen aplicar en cada caso.<\/p>\n<p><strong>&#8211; Desajustes funcionales. <\/strong>Son la causa m\u00e1s com\u00fan<strong>&nbsp;<\/strong>y suelen ser frecuentes en la adolescencia durante los primeros dos o tres a\u00f1os en que se tiene la regla. En esta etapa es normal tener reglas m\u00e1s abundantes (o, al rev\u00e9s, meses en los que no te venga la regla) debido a una inmadurez del sistema hormonal. En algunos casos, y siempre bajo prescripci\u00f3n m\u00e9dica, puede ser necesario recurrir a los anticonceptivos o tomar suplementos de hierro.<\/p>\n<p><strong>&#8211; Perimenopausia. <\/strong>En los \u00faltimos a\u00f1os de la regla, cuando se aproxima la menopausia, tambi\u00e9n pueden producirse desajustes funcionales que pueden provocar cambios en el flujo menstrual: habitualmente, las reglas son m\u00e1s escasas, en cuanto a la cantidad de sangre que se pierde, y m\u00e1s cortas, en su duraci\u00f3n. Pero tambi\u00e9n puede ocurrir lo contrario: es decir, que est\u00e9s varios meses sin que te venga la regla y, de pronto, cuando menos lo esperas -la<em> ley de Murphy <\/em>se cumple-, tener una menstruaci\u00f3n muy copiosa, o varias sucesivas, en un intervalo corto de tiempo. En este caso, tambi\u00e9n es importante informar a tu ginec\u00f3loga\/o, para que confirme si la causa es funcional.<\/p>\n<p><strong>&#8211; Miomas o p\u00f3lipos.&nbsp;<\/strong>Los miomas son tumoraciones benignas, que pueden aparecer en la cavidad uterina y provocar p\u00e9rdidas de sangre coincidiendo o no con la menstruaci\u00f3n. Solo se extirpan cuando son muy grandes, provocan molestias o crecen mucho en muy poco tiempo. Hay f\u00e1rmacos que ayudan a controlar el sangrado. Los p\u00f3lipos tambi\u00e9n suelen ser benignos y pueden provocar sangrado vaginal, pero suelen ser mucho m\u00e1s peque\u00f1os que los miomas (en general, no sobrepasan los 3 cm). En general son m\u00e1s frecuentes entre los 35 y los 50 a\u00f1os, de media. En nuestra web tienes <a href=\"https:\/\/www.dexeus.com\/problemas-ginecologicos\/miomas-polipos\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">m\u00e1s informaci\u00f3n sobre los miomas y p\u00f3lipos<\/span><\/a>.<\/p>\n<p><strong>&#8211; Endometriosis. <\/strong>Es una patolog\u00eda que requiere atenci\u00f3n m\u00e9dica, ya que adem\u00e1s de un sangrado excesivo, puede provocar otros problemas como dolor menstrual,&nbsp;dolor con las relaciones sexuales y\/o comprometer la fertilidad. En nuestro centro contamos con una <a href=\"https:\/\/www.dexeus.com\/problemas-ginecologicos\/endometriosis\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Unidad de Endometriosis<\/span><\/a> y ginec\u00f3logos especializados en el diagn\u00f3stico y tratamiento de esta patolog\u00eda.<\/p>\n<p><strong>&#8211; Anticonceptivos. <\/strong>Seguro que has o\u00eddo decir que el uso del dispositivo intrauterino (DIU) de cobre puede provocar reglas m\u00e1s abundantes, y es verdad, aunque no ocurre en todos los casos. Tambi\u00e9n durante los primeros meses de uso de algunos anticonceptivos hormonales es posible que el flujo menstrual aumente. Si es tu caso, debes informar a tu ginec\u00f3logo\/a y, si no cede con el tiempo, es posible que sea necesario buscar un m\u00e9todo alternativo. En los \u00faltimos a\u00f1os tambi\u00e9n disponemos de los DIUs hormonales, que ayudan a solventar el problema de las reglas abundantes debidas al DIU convencional.<\/p>\n<p><strong>&#8211; Medicamentos.&nbsp;<\/strong>Ciertos medicamentos, como el \u00e1cido acetilsalic\u00edlico y&nbsp;los de acci\u00f3n anticoagulante pueden provocar cambios en el flujo menstrual. Informa a tu ginec\u00f3logo.<\/p>\n<p><div class='et-box et-info'>\n\t\t\t\t\t<div class='et-box-content'><strong>Otras causas<\/strong><\/p>\n<p>Otras causas que pueden provocar sangrado no relacionadas con la menstruaci\u00f3n:<\/p>\n<ul>\n<li>Complicaciones del embarazo: un embarazo ect\u00f3pico o un aborto pueden provocar un sangrado abundante. En estos casos es fundamental acudir a un centro hospitalario lo antes posible.<\/li>\n<li>Trastornos de la coagulaci\u00f3n. La causa puede ser alteraciones en las plaquetas o a enfermedades gen\u00e9ticas o heredadas.<\/li>\n<li>Enfermedades generales: algunas infecciones, enfermedades que afectan al sistema endocrino (como el tiroides), c\u00e1ncer, trastornos renales o algunas intolerancias alimentarias (gluten, lactosa).<\/li>\n<li>Traumatismos por accidentes o lesiones.<\/div><\/div><\/li>\n<\/ul>\n<p>Si tienes problemas con la regla o quieres revolver alguna duda, puedes pedir cita en nuestro centro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La respuesta es no, y las causas pueden ser muchas, pero \u00a1tranquila!, porque en la mayor\u00eda de los casos se debe a un desajuste funcional y suele ser algo temporal. Aunque no por eso hay que pasarlo por alto, ya que un sangrado menstrual excesivo puede indicar la existencia de alg\u00fan problema de salud. Pero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4541,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[425,78,341,1346,1347,127,1344,1345],"_links":{"self":[{"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/posts\/4540"}],"collection":[{"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/comments?post=4540"}],"version-history":[{"count":11,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/posts\/4540\/revisions"}],"predecessor-version":[{"id":638565,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/posts\/4540\/revisions\/638565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/media\/4541"}],"wp:attachment":[{"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/media?parent=4540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/categories?post=4540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dexeus.com\/blog\/wp-json\/wp\/v2\/tags?post=4540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}